{"id":47453,"date":"2023-12-18T15:33:19","date_gmt":"2023-12-18T13:33:19","guid":{"rendered":"http:\/\/lagranjafoods.com\/politique-en-matiere-de-cookies\/"},"modified":"2026-05-21T10:48:06","modified_gmt":"2026-05-21T08:48:06","slug":"politique-en-matiere-de-cookies","status":"publish","type":"page","link":"https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/","title":{"rendered":"Politique en mati\u00e8re de cookies"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Date d\u2019entr\u00e9e en vigueur : 15 mai 2024<\/p>\n\n<h2 class=\"wp-block-heading\">Qu\u2019est-ce que les cookies ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Cette politique de cookies explique ce que sont les cookies et comment nous les utilisons, les types de cookies que nous utilisons (c\u2019est-\u00e0-dire les informations que nous recueillons via les cookies et comment ces informations sont utilis\u00e9es) ainsi que comment g\u00e9rer vos param\u00e8tres de cookies.  <\/p>\n\n<p class=\"wp-block-paragraph\">Les cookies sont de petits fichiers texte utilis\u00e9s pour stocker de petits morceaux d\u2019information. Ils sont stock\u00e9s sur votre appareil lorsque le site web est charg\u00e9 dans votre navigateur.   <\/p>\n\n<p class=\"wp-block-paragraph\">Ces cookies nous aident \u00e0 faire fonctionner correctement le site, \u00e0 le rendre plus s\u00e9curis\u00e9, \u00e0 offrir une meilleure exp\u00e9rience utilisateur et \u00e0 comprendre comment le site fonctionne afin d\u2019analyser ce qui fonctionne et o\u00f9 il doit \u00eatre am\u00e9lior\u00e9.<\/p>\n\n<h2 class=\"wp-block-heading\">Comment utilisons-nous les cookies ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Comme la plupart des services en ligne, notre site web utilise ses propres cookies et des cookies tiers pour diverses fins. Les cookies de premi\u00e8re partie sont principalement n\u00e9cessaires au bon fonctionnement du site et ne collectent aucune de vos donn\u00e9es personnelles identifiables.   <\/p>\n\n<p class=\"wp-block-paragraph\">Les cookies tiers utilis\u00e9s sur notre site web servent principalement \u00e0 comprendre le fonctionnement du site, comment vous interagissez avec notre site, la s\u00e9curit\u00e9 de nos services, la diffusion de publicit\u00e9s pertinentes pour vous, et au final vous offrent une meilleure exp\u00e9rience utilisateur et acc\u00e9l\u00e9rent vos futures interactions avec notre site.<\/p>\n<p>[wcc_category_list]<\/p>\n\n<h2 class=\"wp-block-heading\">G\u00e9rer les pr\u00e9f\u00e9rences de cookies<\/h2>\n\n<p class=\"wp-block-paragraph\">Vous pouvez modifier vos pr\u00e9f\u00e9rences de cookies \u00e0 tout moment en cliquant sur le bouton [wcc_preference_button]. Cela vous permettra de revenir sur la banni\u00e8re de consentement aux cookies et de modifier vos pr\u00e9f\u00e9rences ou de retirer votre consentement imm\u00e9diatement. De plus, diff\u00e9rents navigateurs proposent diff\u00e9rentes m\u00e9thodes pour bloquer et supprimer les cookies utilis\u00e9s par les sites web. Vous pouvez modifier les param\u00e8tres de votre navigateur pour bloquer ou supprimer les cookies. Vous trouverez ci-dessous des liens vers des documents de soutien sur la gestion et la suppression des cookies issus des principaux navigateurs web.    <\/p>\n\n<p class=\"wp-block-paragraph\">Chrome : <a href=\"https:\/\/support.google.com\/accounts\/answer\/32050\">https:\/\/support.google.com\/accounts\/answer\/32050<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Safari : <a href=\"https:\/\/support.apple.com\/en-in\/guide\/safari\/sfri11471\/mac\">https:\/\/support.apple.com\/es-es\/guide\/safari\/sfri11471\/mac<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Firefox : <a href=\"https:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-sitios-web-rastrear-preferencias\">https:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-sitios-web-rastrear-preferencias<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Microsoft Edge : <a href=\"https:\/\/support.microsoft.com\/en-us\/microsoft-edge\/delete-cookies-in-microsoft-edge-63947406-40ac-c3b8-57b9-2a946a29ae09\">Supprimer les cookies dans Microsoft Edge &#8211; Support Microsoft<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Si vous utilisez un autre navigateur web, veuillez consulter les documents officiels de support de votre navigateur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Date d\u2019entr\u00e9e en vigueur : 15 mai 2024 Qu\u2019est-ce que les cookies ? Cette politique de cookies explique ce que sont les cookies et comment nous les utilisons, les types &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-47453","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique en mati\u00e8re de cookies - La Granja Foods<\/title>\n<meta name=\"description\" content=\"Date d\u2019entr\u00e9e en vigueur : 15 mai 2024 Qu\u2019est-ce que les cookies ? Cette politique de cookies explique ce que sont les cookies et comment nous les\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique en mati\u00e8re de cookies - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"Date d\u2019entr\u00e9e en vigueur : 15 mai 2024 Qu\u2019est-ce que les cookies ? Cette politique de cookies explique ce que sont les cookies et comment nous les\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-21T08:48:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/\",\"name\":\"Politique en mati\u00e8re de cookies - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/#website\"},\"datePublished\":\"2023-12-18T13:33:19+00:00\",\"dateModified\":\"2026-05-21T08:48:06+00:00\",\"description\":\"Date d\u2019entr\u00e9e en vigueur : 15 mai 2024 Qu\u2019est-ce que les cookies ? Cette politique de cookies explique ce que sont les cookies et comment nous les\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique en mati\u00e8re de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique en mati\u00e8re de cookies - La Granja Foods","description":"Date d\u2019entr\u00e9e en vigueur : 15 mai 2024 Qu\u2019est-ce que les cookies ? Cette politique de cookies explique ce que sont les cookies et comment nous les","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique en mati\u00e8re de cookies - La Granja Foods","og_description":"Date d\u2019entr\u00e9e en vigueur : 15 mai 2024 Qu\u2019est-ce que les cookies ? Cette politique de cookies explique ce que sont les cookies et comment nous les","og_url":"https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/","og_site_name":"La Granja Foods","article_modified_time":"2026-05-21T08:48:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/","url":"https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/","name":"Politique en mati\u00e8re de cookies - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/fr\/#website"},"datePublished":"2023-12-18T13:33:19+00:00","dateModified":"2026-05-21T08:48:06+00:00","description":"Date d\u2019entr\u00e9e en vigueur : 15 mai 2024 Qu\u2019est-ce que les cookies ? Cette politique de cookies explique ce que sont les cookies et comment nous les","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/fr\/politique-en-matiere-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique en mati\u00e8re de cookies"}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/fr\/#website","url":"https:\/\/lagranjafoods.com\/fr\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/fr\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lagranjafoods.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/fr\/wp-json\/wp\/v2\/pages\/47453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lagranjafoods.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/fr\/wp-json\/wp\/v2\/comments?post=47453"}],"version-history":[{"count":0,"href":"https:\/\/lagranjafoods.com\/fr\/wp-json\/wp\/v2\/pages\/47453\/revisions"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/fr\/wp-json\/wp\/v2\/media?parent=47453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}