{"id":57488,"date":"2026-06-09T09:16:42","date_gmt":"2026-06-09T07:16:42","guid":{"rendered":"http:\/\/lagranjafoods.com\/?post_type=product&#038;p=57488"},"modified":"2026-07-06T12:06:51","modified_gmt":"2026-07-06T10:06:51","slug":"bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr","status":"publish","type":"product","link":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/","title":{"rendered":"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr."},"content":{"rendered":"<p>Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr. Desde el primer d\u00eda, elaborar los productos lo mejor que sabemos y asegurar un gran sabor ha sido para nosotros un valor irrenunciable.<\/p>\n<p>En 1954 nuestros abuelos ten\u00edan un colmado junto a su peque\u00f1a granja de gallinas. En \u00e9l vend\u00edan al vecindario los huevos as\u00ed como v\u00edveres de todo tipo. Una vez la tienda se qued\u00f3 sin suministro de magdalenas, uno de sus productos m\u00e1s populares. Para contentar a la clientela, nuestra abuela decidi\u00f3 hornear su propia receta de magdalenas en la cocina de su casa. Su enorme \u00e9xito sorprendi\u00f3 a todos, cada vez se vend\u00edan m\u00e1s y m\u00e1s. De ah\u00ed naci\u00f3 La Granja y aprendimos algo que siempre tenemos presente: trabajar fuerte y hacerlo todo lo mejor que uno sabe para satisfacer a tus clientes.<\/p>\n<p>Fue as\u00ed con las primeras especialidades tradicionales que nos dieron a conocer y lo ha seguido siendo a lo largo de nuestra trayectoria, al incorporar continuamente novedades en nuestra gama.<\/p>\n<p>Avanzarnos a las necesidades y deseos de los consumidores nos ha convertido en un referente de calidad e innovaci\u00f3n en nuestro sector de productos de alimentaci\u00f3n. En los a\u00f1os 80 <a href=\"http:\/\/lagranjafoods.com\/\">La Granja<\/a> fue pionera al crear especialidades atendiendo a distintas necesidades diet\u00e9ticas, que hoy forman parte de nuestra gama Diet.<\/p>\n<p>M\u00e1s tarde lanzamos la gama Bio, que utiliza solo ingredientes de la agricultura ecol\u00f3gica. Han seguido a esta l\u00ednea, la gama Vegan para un consumo estrictamente vegano y los productos Sin Gluten y Sin Lactosa, que tienen una producci\u00f3n separada a la resta de productos.<\/p>\n<p>En los productos de esta nueva gama utilizamos \u00fanicamente ingredientes libres de gluten, lactosa y ma\u00edz. Aseguramos su no-contaminaci\u00f3n en todo el proceso, desde una producci\u00f3n separada del resto. Este producto cuenta con el sello de La <a href=\"https:\/\/celiacos.org\/que-hacemos\/certificacion-alimentaria-sin-gluten\/sistema-de-licencia-europeo-els-o-espiga-barrada\/\">Espiga Barrada<\/a> y n\u00famero de licencia ES-055-006, certificado por la AOECS (Asociaci\u00f3n de Sociedades de Celiacos de Europa).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disfruta de nuestro Bizcocho Especial de Coco y Pl\u00e1tano Sin Gluten en su nuevo formato de 230 g, una pr\u00e1ctica bolsa que contiene 4 deliciosos trozos de bizcocho listos para disfrutar en cualquier momento. La combinaci\u00f3n tropical del coco rallado natural con la dulzura del pl\u00e1tano convierte cada bocado en un aut\u00e9ntico capricho para los sentidos, con una textura tierna y esponjosa. Una opci\u00f3n deliciosa e ideal para quienes buscan sabores ex\u00f3ticos.<\/p>\n<ul>\n<li aria-level=\"1\">Sin gluten<\/li>\n<li aria-level=\"1\">Sin lactosa<\/li>\n<li aria-level=\"1\">Sin prote\u00edna de leche de vaca<\/li>\n<li aria-level=\"1\">Sin ma\u00edz<\/li>\n<li aria-level=\"1\">Sin aceite de palma<\/li>\n<li>Elaborado con coco rallado natural<\/li>\n<li aria-level=\"1\">Elaborado con huevos frescos<\/li>\n<li aria-level=\"1\">Horneado lentamente<\/li>\n<li aria-level=\"1\">Elevada esponjosidad y sabor<\/li>\n<li aria-level=\"1\">Textura muy tierna<\/li>\n<li aria-level=\"1\">Contiene fibras vegetales y c\u00e1scara psyllium<\/li>\n<\/ul>\n<p>Bolsa de 350 gr.<\/p>\n","protected":false},"featured_media":57970,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[33],"product_tag":[44],"class_list":["post-57488","product","type-product","status-publish","has-post-thumbnail","product_cat-sin-gluten","product_tag-sin-gluten","pa_marca-la-granja","pa_tipologia-bizcochos","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr. - La Granja Foods<\/title>\n<meta name=\"description\" content=\"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa. Desde el primer d\u00eda, elaborar los productos lo mejor que sabemos y asegurar un gran sabor\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr. - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa. Desde el primer d\u00eda, elaborar los productos lo mejor que sabemos y asegurar un gran sabor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T10:06:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-coco-y-platan-230g.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1692\" \/>\n\t<meta property=\"og:image:height\" content=\"2022\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\\\/\",\"name\":\"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr. - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-coco-y-platan-230g.png\",\"datePublished\":\"2026-06-09T07:16:42+00:00\",\"dateModified\":\"2026-07-06T10:06:51+00:00\",\"description\":\"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa. Desde el primer d\u00eda, elaborar los productos lo mejor que sabemos y asegurar un gran sabor\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-coco-y-platan-230g.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-coco-y-platan-230g.png\",\"width\":1692,\"height\":2022},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr. - La Granja Foods","description":"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa. Desde el primer d\u00eda, elaborar los productos lo mejor que sabemos y asegurar un gran sabor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/","og_locale":"es_ES","og_type":"article","og_title":"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr. - La Granja Foods","og_description":"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa. Desde el primer d\u00eda, elaborar los productos lo mejor que sabemos y asegurar un gran sabor","og_url":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/","og_site_name":"La Granja Foods","article_modified_time":"2026-07-06T10:06:51+00:00","og_image":[{"width":1692,"height":2022,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-coco-y-platan-230g.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/","url":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/","name":"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr. - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-coco-y-platan-230g.png","datePublished":"2026-06-09T07:16:42+00:00","dateModified":"2026-07-06T10:06:51+00:00","description":"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa. Desde el primer d\u00eda, elaborar los productos lo mejor que sabemos y asegurar un gran sabor","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-coco-y-platan-230g.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-coco-y-platan-230g.png","width":1692,"height":2022},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/es\/producto\/bizcocho-especial-coco-y-platano-sin-gluten-y-sin-lactosa-230gr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/lagranjafoods.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Bizcocho especial coco y pl\u00e1tano sin gluten y sin lactosa 230 gr."}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/es\/#website","url":"https:\/\/lagranjafoods.com\/es\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/es\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product\/57488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/comments?post=57488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/media\/57970"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/media?parent=57488"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product_cat?post=57488"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product_tag?post=57488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}