{"id":4979,"date":"2024-06-06T14:52:10","date_gmt":"2024-06-06T14:52:10","guid":{"rendered":"http:\/\/lagranjafoods.com\/?post_type=product&#038;p=4979"},"modified":"2026-05-29T11:41:14","modified_gmt":"2026-05-29T09:41:14","slug":"lata-bombones-de-chocolate","status":"publish","type":"product","link":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/","title":{"rendered":"Lata Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas"},"content":{"rendered":"<div class=\"vtex-flex-layout-0-x-flexRow vtex-flex-layout-0-x-flexRow--corporate-pages-item vtex-flex-layout-0-x-flexRow--corporate-pages-headboard\">\n<section class=\"vtex-store-components-3-x-container ph3 ph5-m ph2-xl mw9 center \">\n<div class=\"flex mt0 mb0 pt0 pb0 justify-start vtex-flex-layout-0-x-flexRowContent vtex-flex-layout-0-x-flexRowContent--corporate-pages-item vtex-flex-layout-0-x-flexRowContent--corporate-pages-headboard items-stretch w-100\">\n<div class=\"pr0 items-stretch vtex-flex-layout-0-x-stretchChildrenWidth flex\">\n<div class=\"vtex-rich-text-0-x-container vtex-rich-text-0-x-container--corporate-pages-headboard vtex-rich-text-0-x-container--corporate-pages-headboard-content flex tl items-start justify-start t-body c-on-base\">\n<div class=\"vtex-rich-text-0-x-wrapper vtex-rich-text-0-x-wrapper--corporate-pages-headboard vtex-rich-text-0-x-wrapper--corporate-pages-headboard-content\">\n<p class=\"lh-copy vtex-rich-text-0-x-paragraph vtex-rich-text-0-x-paragraph--corporate-pages-headboard vtex-rich-text-0-x-paragraph--corporate-pages-headboard-content\">Lata bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas. Autenticidad, proximidad y calidad definen<a href=\"https:\/\/www.simoncoll.com\/es\/sobre-simon-coll\"> Sim\u00f3n Coll.<\/a> Seis generaciones familiares han contribuido en mantener el esp\u00edritu de nuestro oficio desde 1840 y en continuar trasladando la cultura del chocolate y el cacao de una manera \u00fanica y sin precedentes. Garantizar el sabor y la excelencia de nuestros productos son las premisas por las que, constantemente, continuamos innovando en f\u00f3rmulas y procedimientos propios.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<div class=\"vtex-flex-layout-0-x-flexRow vtex-flex-layout-0-x-flexRow--corporate-pages-item vtex-flex-layout-0-x-flexRow--info-card-corporate-pages vtex-flex-layout-0-x-flexRow--info-card-corporate-pages-left\">\n<section class=\"vtex-store-components-3-x-container ph3 ph5-m ph2-xl mw9 center \">\n<div class=\"flex mt0 mb0 pt0 pb0 justify-start vtex-flex-layout-0-x-flexRowContent vtex-flex-layout-0-x-flexRowContent--corporate-pages-item vtex-flex-layout-0-x-flexRowContent--info-card-corporate-pages vtex-flex-layout-0-x-flexRowContent--info-card-corporate-pages-left items-stretch w-100\">\n<div class=\"pr0 items-stretch vtex-flex-layout-0-x-stretchChildrenWidth flex\">\n<div class=\"vtex-store-components-3-x-infoCardContainer vtex-store-components-3-x-infoCardContainer--info-card-corporate-pages vtex-store-components-3-x-infoCardContainer--info-card-corporate-pages-left items-center flex-ns flex-row bg-base ph2-ns pb2 justify-between\" data-testid=\"container\">\n<div class=\"vtex-store-components-3-x-infoCardTextContainer vtex-store-components-3-x-infoCardTextContainer--info-card-corporate-pages vtex-store-components-3-x-infoCardTextContainer--info-card-corporate-pages-left flex flex-column mw-100 w-50-ns ph3-s items-start pr4-ns\">\n<div class=\"vtex-store-components-3-x-infoCardSubhead vtex-store-components-3-x-infoCardSubhead--info-card-corporate-pages vtex-store-components-3-x-infoCardSubhead--info-card-corporate-pages-left t-body mt6 c-on-base tl mw-100\">\n<div>M\u00e1s de 180 a\u00f1os de experiencia como maestros chocolateros y elaboradores. De una manera artesanal y cuidando cada detalle, seguimos compartiendo esta pasi\u00f3n y saber hacer desde Sant Sadurn\u00ed d&#8217;Anoia (Barcelona), el punto de partida de Sim\u00f3n Coll y desde donde continuamos escribiendo nuestra historia. Sim\u00f3n Coll chocolates y Chocolate Amatller dan paso a casi dos siglos de historia, d\u00f3nde la constancia, la innovaci\u00f3n y la calidad de los productos forman parte de nuestro ADN.<\/div>\n<\/div>\n<div><\/div>\n<div>Dedicaci\u00f3n, innovaci\u00f3n y formulaci\u00f3n son sin\u00f3nimos del proceso de elaboraci\u00f3n de Sim\u00f3n Coll. Muchos de los m\u00e9todos que se utilizan conservan caracter\u00edsticas propias diferenciales, fruto de criterios profesionales s\u00f3lidamente establecidos en el tiempo. Sum\u00e9rgete en el mundo del chocolate y conoce el proceso Bean to Bar.<\/div>\n<div><\/div>\n<\/div>\n<div>Trasladamos nuestro compromiso y saber hacer de una manera \u00e9tica y responsable. Estamos comprometidos con el medio ambiente y promovemos procesos que favorecen al entorno. apoyamos iniciativas que integran a personas vulnerables al mundo laboral de la mano de entidades ben\u00e9ficas. Participamos activamente con fundaciones sin \u00e1nimo de lucro para promover iniciativas sociales.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Descubre el bomb\u00f3n de cremoso chocolate con leche, suave pralin\u00e9 de avellana, crocante caramelizado y punto salino final presentado en una elegante lata de 20 bombones cada uno envuelto en su flowpack individual, de la casa Sim\u00f3n Coll.<\/p>\n<p>El regalo perfecto, donde se combina la delicadeza y buen gusto de un bomb\u00f3n excepcional junto con un bonito y llamativo dise\u00f1o. Nuestro bomb\u00f3n est\u00e1 elaborado con caracter\u00edsticas \u00fanicas: con ingredientes nobles seleccionados, sin aceite de palma, sin conservantes y sin gluten.<\/p>\n<ul>\n<li aria-level=\"1\">Sin gluten<\/li>\n<li aria-level=\"1\">Sin aceite de palma<\/li>\n<li aria-level=\"1\">Chocolate Sim\u00f3n Coll<\/li>\n<li aria-level=\"1\">Perfecto para regalar<\/li>\n<\/ul>\n<p>Formato: 180 gr.<\/p>\n","protected":false},"featured_media":33642,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[94],"product_tag":[44],"class_list":["post-4979","product","type-product","status-publish","has-post-thumbnail","product_cat-marcas-amigas","product_tag-sin-gluten","pa_lata-180-gr","pa_marca-simon-coll","pa_tipologia-bombones","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lata Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas - La Granja Foods<\/title>\n<meta name=\"description\" content=\"Lata bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas. Autenticidad, proximidad y calidad definen Sim\u00f3n Coll. Seis generaciones familiares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lata Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"Lata bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas. Autenticidad, proximidad y calidad definen Sim\u00f3n Coll. Seis generaciones familiares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T09:41:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Lata-bombones-praline.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1481\" \/>\n\t<meta property=\"og:image:height\" content=\"1769\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/lata-bombones-de-chocolate\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/lata-bombones-de-chocolate\\\/\",\"name\":\"Lata Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/lata-bombones-de-chocolate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/lata-bombones-de-chocolate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Lata-bombones-praline.png\",\"datePublished\":\"2024-06-06T14:52:10+00:00\",\"dateModified\":\"2026-05-29T09:41:14+00:00\",\"description\":\"Lata bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas. Autenticidad, proximidad y calidad definen Sim\u00f3n Coll. Seis generaciones familiares.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/lata-bombones-de-chocolate\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/lata-bombones-de-chocolate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/lata-bombones-de-chocolate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Lata-bombones-praline.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Lata-bombones-praline.png\",\"width\":1481,\"height\":1769,\"caption\":\"Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/lata-bombones-de-chocolate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lata Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lata Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas - La Granja Foods","description":"Lata bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas. Autenticidad, proximidad y calidad definen Sim\u00f3n Coll. Seis generaciones familiares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/","og_locale":"es_ES","og_type":"article","og_title":"Lata Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas - La Granja Foods","og_description":"Lata bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas. Autenticidad, proximidad y calidad definen Sim\u00f3n Coll. Seis generaciones familiares.","og_url":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/","og_site_name":"La Granja Foods","article_modified_time":"2026-05-29T09:41:14+00:00","og_image":[{"width":1481,"height":1769,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Lata-bombones-praline.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/","url":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/","name":"Lata Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Lata-bombones-praline.png","datePublished":"2024-06-06T14:52:10+00:00","dateModified":"2026-05-29T09:41:14+00:00","description":"Lata bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas. Autenticidad, proximidad y calidad definen Sim\u00f3n Coll. Seis generaciones familiares.","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Lata-bombones-praline.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Lata-bombones-praline.png","width":1481,"height":1769,"caption":"Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas"},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/es\/producto\/lata-bombones-de-chocolate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/lagranjafoods.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Lata Bombones de Chocolate con Leche y Pralin\u00e9 de Avellanas"}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/es\/#website","url":"https:\/\/lagranjafoods.com\/es\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/es\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product\/4979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/comments?post=4979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/media\/33642"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/media?parent=4979"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product_cat?post=4979"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product_tag?post=4979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}