{"id":4409,"date":"2024-06-06T14:35:57","date_gmt":"2024-06-06T14:35:57","guid":{"rendered":"http:\/\/lagranjafoods.com\/product\/bombones-de-praline\/"},"modified":"2026-07-01T12:09:42","modified_gmt":"2026-07-01T10:09:42","slug":"bombones-de-praline","status":"publish","type":"product","link":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/","title":{"rendered":"Bombones de Pralin\u00e9"},"content":{"rendered":"<p>Bombones de Pralin\u00e9. En<a href=\"http:\/\/lagranjafoods.com\/nosotros-historia\/\"> La Granja Foods<\/a> siempre buscamos productos que sorprendan y deleiten a nuestros clientes, por eso estamos encantados de colaborar con <strong>Mi&amp;Cu<\/strong>, una marca especializada en la creaci\u00f3n de los inigualables bombones <a href=\"http:\/\/lagranjafoods.com\/marca\/bombones-micu\/\"><strong>Marlonas<\/strong><\/a>. Estos bombones se han ganado un lugar especial en el mundo de la confiter\u00eda gracias a su distintiva mezcla de sabores y texturas.<\/p>\n<p>Mi&amp;Cu se distingue por su innovaci\u00f3n y dedicaci\u00f3n a la excelencia, utilizando solo los ingredientes m\u00e1s selectos para crear bombones que no solo saben bien, sino que tambi\u00e9n cuentan una historia de pasi\u00f3n por el chocolate. Ahora, tienes la oportunidad de experimentar la magia de los bombones Marlonas a trav\u00e9s de nuestra tienda online.<\/p>\n<p>Desde sabores cl\u00e1sicos hasta combinaciones m\u00e1s atrevidas, cada bomb\u00f3n Marlonas es una obra maestra de sabor que ofrece una experiencia gustativa \u00fanica. Nos complace ser parte de esta deliciosa aventura, tray\u00e9ndote un producto que redefine lo que significa disfrutar de un buen chocolate.<\/p>\n<p>MI&amp;CU Gourmet es una empresa familiar cercana a Barcelona fundada por los hermanos Miret, N\u00faria y Josep. Provienen de una larga tradici\u00f3n familiar del chocolate de m\u00e1s de 70 a\u00f1os y suman 20 a\u00f1os de experiencia en el sector del chocolate gourmet.<\/p>\n<p>En nuestros productos combinamos el uso de materias primas de calidad mediterr\u00e1nea, principalmente las almendras, con sabores cl\u00e1sicos, como la gama Marlonas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-size: 16px;\">Del\u00edcias de chocolate de almendra caramelizada del Mediterr\u00e1neo con Pralin\u00e9 de avellanas y almendras cubiertas de cacaco en polvo.<\/span><\/p>\n<p>De la mezcla del rinc\u00f3n m\u00e1s dulce de la mar Mediterr\u00e1neo y la ciudad de Barcelona nace Marlona. Un bomb\u00f3n de chocolate y almendras que traslada a tu paladar los sabores m\u00e1s representativos de la bomboner\u00eda tradicional que gustan a todos. Una creaci\u00f3n exquisita para tu paladar y una opci\u00f3n donde el placer est\u00e1 garantizado.<\/p>\n<p>\u00a1Esta combinaci\u00f3n est\u00e1 dedicado a los amantes del chocolate m\u00e1s puro! Deja que esta delicia de cacao y gianduia te brinde un momento de sabor intenso.<\/p>\n<p>\u00abTenemos claro que para obtener el mejor resultado posible, necesitamos <b>materias primas de gran calidad<\/b>, el chocolate y los frutos secos son la base de nuestras creaciones m\u00e1s cl\u00e1sicas como la gamma Marlona Classic.\u00a0Utilizamos almendras del pa\u00eds, por su innegable calidad y para ser un referente culinario de nuestra <b>dieta mediterr\u00e1nea<\/b> reconocida mundialmente.\u00bb<\/p>\n<p>\u00a1Este producto es libre de gluten!<\/p>\n<ul>\n<li>Sin gluten<\/li>\n<li>Con almendras del pa\u00eds<\/li>\n<li aria-level=\"1\">Con ingredientes de m\u00e1xima calidad<\/li>\n<li aria-level=\"1\">Cubiertas de cacao en polvo<\/li>\n<li aria-level=\"1\">Elaboradas con chocolate premium<\/li>\n<\/ul>\n<p>Caja de 30 gr.<\/p>\n","protected":false},"featured_media":33225,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[94],"product_tag":[129],"class_list":["post-4409","product","type-product","status-publish","has-post-thumbnail","product_cat-marcas-amigas","product_tag-chocolate","pa_marca-la-granja","pa_marca-bombones-micu","pa_tipologia-bombones","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bombones de Pralin\u00e9 - La Granja Foods<\/title>\n<meta name=\"description\" content=\"Bombones de Pralin\u00e9. Siempre buscamos productos que sorprendan y deleiten a nuestros clientes, por eso estamos encantados de colaborar con Mi&amp;Cu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bombones de Pralin\u00e9 - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"Bombones de Pralin\u00e9. Siempre buscamos productos que sorprendan y deleiten a nuestros clientes, por eso estamos encantados de colaborar con Mi&amp;Cu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T10:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Caja-30gr--marlonas-IV-1-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1692\" \/>\n\t<meta property=\"og:image:height\" content=\"2022\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bombones-de-praline\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bombones-de-praline\\\/\",\"name\":\"Bombones de Pralin\u00e9 - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bombones-de-praline\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bombones-de-praline\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Caja-30gr--marlonas-IV-1-3.jpg\",\"datePublished\":\"2024-06-06T14:35:57+00:00\",\"dateModified\":\"2026-07-01T10:09:42+00:00\",\"description\":\"Bombones de Pralin\u00e9. Siempre buscamos productos que sorprendan y deleiten a nuestros clientes, por eso estamos encantados de colaborar con Mi&Cu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bombones-de-praline\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bombones-de-praline\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bombones-de-praline\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Caja-30gr--marlonas-IV-1-3.jpg\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Caja-30gr--marlonas-IV-1-3.jpg\",\"width\":1692,\"height\":2022,\"caption\":\"Bombones de Pralin\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/producto\\\/bombones-de-praline\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bombones de Pralin\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bombones de Pralin\u00e9 - La Granja Foods","description":"Bombones de Pralin\u00e9. Siempre buscamos productos que sorprendan y deleiten a nuestros clientes, por eso estamos encantados de colaborar con Mi&Cu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/","og_locale":"es_ES","og_type":"article","og_title":"Bombones de Pralin\u00e9 - La Granja Foods","og_description":"Bombones de Pralin\u00e9. Siempre buscamos productos que sorprendan y deleiten a nuestros clientes, por eso estamos encantados de colaborar con Mi&Cu.","og_url":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/","og_site_name":"La Granja Foods","article_modified_time":"2026-07-01T10:09:42+00:00","og_image":[{"width":1692,"height":2022,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Caja-30gr--marlonas-IV-1-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/","url":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/","name":"Bombones de Pralin\u00e9 - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Caja-30gr--marlonas-IV-1-3.jpg","datePublished":"2024-06-06T14:35:57+00:00","dateModified":"2026-07-01T10:09:42+00:00","description":"Bombones de Pralin\u00e9. Siempre buscamos productos que sorprendan y deleiten a nuestros clientes, por eso estamos encantados de colaborar con Mi&Cu.","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Caja-30gr--marlonas-IV-1-3.jpg","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Caja-30gr--marlonas-IV-1-3.jpg","width":1692,"height":2022,"caption":"Bombones de Pralin\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/es\/producto\/bombones-de-praline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/lagranjafoods.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Bombones de Pralin\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/es\/#website","url":"https:\/\/lagranjafoods.com\/es\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/es\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product\/4409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/comments?post=4409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/media\/33225"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/media?parent=4409"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product_cat?post=4409"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/product_tag?post=4409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}