{"id":1133,"date":"2022-11-10T11:58:35","date_gmt":"2022-11-10T11:58:35","guid":{"rendered":"http:\/\/lagranjafoods.com\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/"},"modified":"2025-01-31T15:09:07","modified_gmt":"2025-01-31T15:09:07","slug":"hummus-de-boniato-con-vegan-snacks-de-lentejas","status":"publish","type":"post","link":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/","title":{"rendered":"Hummus de Boniato con Vegan Snacks de Lentejas"},"content":{"rendered":"<h2><span style=\"font-weight: 400;\">INGREDIENTES<\/span><\/h2>\n<ul>\n<li>Vegan Snacks de Lentejas La Granja<\/li>\n<li>150 gr. de garbanzos cocidos escurridos<\/li>\n<li>2 boniatos medianos<\/li>\n<li>1 cucharada sopera de Tahini<\/li>\n<li>1 diente de ajo<\/li>\n<li>Zumo de un lim\u00f3n peque\u00f1o<\/li>\n<li>Sal al gusto<\/li>\n<li>Agua<\/li>\n<li>Aceite de Oliva Virgen Extra<\/li>\n<li>Pimienta roja dulce<\/li>\n<\/ul>\n<h2><span style=\"font-weight: 400;\">ELABORACI\u00d3N<\/span><\/h2>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Calienta el horno a 200\u00baC con calor arriba y abajo. Mientras se calienta el horno, lava bien los boniatos para quitarles toda la tierra. Sobre una bandeja de horno coloca papel vegetal y los boniatos. M\u00e9telos en el horno durante 50 minutos aproximadamente.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Cuando los boniatos est\u00e9n cocidos y tiernos, d\u00e9jalos enfriar hasta que est\u00e9n a temperatura ambiente.<\/li>\n<li aria-level=\"1\">Incorpora todos los ingredientes en un recipiente e introduce los boniatos sin piel. Con una batidora tritura los ingredientes hasta conseguir una mezcla homog\u00e9nea.<\/li>\n<li aria-level=\"1\">Es el momento de rectificar un poco la textura. Si ves que la mezcla ha quedado muy espesa, puedes a\u00f1adir un poco de agua. Modifica tambi\u00e9n de sal al gusto.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">\u00a1Ahora vamos a presentarlo! Sobre un plato o bol incorpora el humus, la pimienta roja dulce y el aceite de oliva Virgen Extra. Y para decorar utiliza, por ejemplo, semillas de ch\u00eda.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Ya solo queda disfrutarlo con los Vegan Snacks de Lentejas de La Granja.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>INGREDIENTES Vegan Snacks de Lentejas La Granja 150 gr. de garbanzos cocidos escurridos 2 boniatos medianos 1 cucharada sopera de Tahini 1 diente de ajo Zumo de un lim\u00f3n peque\u00f1o &hellip;<\/p>\n","protected":false},"author":1,"featured_media":845,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[75],"tags":[],"class_list":["post-1133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hummus de Boniato con Vegan Snacks de Lentejas - La Granja Foods<\/title>\n<meta name=\"description\" content=\"INGREDIENTES Vegan Snacks de Lentejas La Granja 150 gr. de garbanzos cocidos escurridos 2 boniatos medianos 1 cucharada sopera de Tahini 1 diente de ajo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hummus de Boniato con Vegan Snacks de Lentejas - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"INGREDIENTES Vegan Snacks de Lentejas La Granja 150 gr. de garbanzos cocidos escurridos 2 boniatos medianos 1 cucharada sopera de Tahini 1 diente de ajo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-10T11:58:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-31T15:09:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/20-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"emfasi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"emfasi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/\"},\"author\":{\"name\":\"emfasi\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/person\\\/8620ca73cfc2e9a8afd326de202a03db\"},\"headline\":\"Hummus de Boniato con Vegan Snacks de Lentejas\",\"datePublished\":\"2022-11-10T11:58:35+00:00\",\"dateModified\":\"2025-01-31T15:09:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/\"},\"wordCount\":214,\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/20-1.jpg\",\"articleSection\":[\"Recetas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/\",\"name\":\"Hummus de Boniato con Vegan Snacks de Lentejas - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/20-1.jpg\",\"datePublished\":\"2022-11-10T11:58:35+00:00\",\"dateModified\":\"2025-01-31T15:09:07+00:00\",\"description\":\"INGREDIENTES Vegan Snacks de Lentejas La Granja 150 gr. de garbanzos cocidos escurridos 2 boniatos medianos 1 cucharada sopera de Tahini 1 diente de ajo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/20-1.jpg\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/20-1.jpg\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/hummus-de-boniato-con-vegan-snacks-de-lentejas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hummus de Boniato con Vegan Snacks de Lentejas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/es\\\/#\\\/schema\\\/person\\\/8620ca73cfc2e9a8afd326de202a03db\",\"name\":\"emfasi\",\"sameAs\":[\"http:\\\/\\\/lagranjafoods.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hummus de Boniato con Vegan Snacks de Lentejas - La Granja Foods","description":"INGREDIENTES Vegan Snacks de Lentejas La Granja 150 gr. de garbanzos cocidos escurridos 2 boniatos medianos 1 cucharada sopera de Tahini 1 diente de ajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/","og_locale":"es_ES","og_type":"article","og_title":"Hummus de Boniato con Vegan Snacks de Lentejas - La Granja Foods","og_description":"INGREDIENTES Vegan Snacks de Lentejas La Granja 150 gr. de garbanzos cocidos escurridos 2 boniatos medianos 1 cucharada sopera de Tahini 1 diente de ajo","og_url":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/","og_site_name":"La Granja Foods","article_published_time":"2022-11-10T11:58:35+00:00","article_modified_time":"2025-01-31T15:09:07+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/20-1.jpg","type":"image\/jpeg"}],"author":"emfasi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"emfasi","Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/#article","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/"},"author":{"name":"emfasi","@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/person\/8620ca73cfc2e9a8afd326de202a03db"},"headline":"Hummus de Boniato con Vegan Snacks de Lentejas","datePublished":"2022-11-10T11:58:35+00:00","dateModified":"2025-01-31T15:09:07+00:00","mainEntityOfPage":{"@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/"},"wordCount":214,"publisher":{"@id":"https:\/\/lagranjafoods.com\/es\/#organization"},"image":{"@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/20-1.jpg","articleSection":["Recetas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/","url":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/","name":"Hummus de Boniato con Vegan Snacks de Lentejas - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/20-1.jpg","datePublished":"2022-11-10T11:58:35+00:00","dateModified":"2025-01-31T15:09:07+00:00","description":"INGREDIENTES Vegan Snacks de Lentejas La Granja 150 gr. de garbanzos cocidos escurridos 2 boniatos medianos 1 cucharada sopera de Tahini 1 diente de ajo","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/20-1.jpg","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/20-1.jpg","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/es\/hummus-de-boniato-con-vegan-snacks-de-lentejas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hummus de Boniato con Vegan Snacks de Lentejas"}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/es\/#website","url":"https:\/\/lagranjafoods.com\/es\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/es\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lagranjafoods.com\/es\/#\/schema\/person\/8620ca73cfc2e9a8afd326de202a03db","name":"emfasi","sameAs":["http:\/\/lagranjafoods.com"]}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/posts\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/comments?post=1133"}],"version-history":[{"count":0,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/posts\/1133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/media\/845"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/media?parent=1133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/categories?post=1133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/es\/wp-json\/wp\/v2\/tags?post=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}