{"id":8903,"date":"2024-06-06T15:03:56","date_gmt":"2024-06-06T15:03:56","guid":{"rendered":"http:\/\/lagranjafoods.com\/product\/pa-de-pessic-amb-te-matxa-de-tea-shop\/"},"modified":"2026-05-29T12:33:18","modified_gmt":"2026-05-29T10:33:18","slug":"pa-de-pessic-amb-te-matxa-de-tea-shop","status":"publish","type":"product","link":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/","title":{"rendered":"Pa de pessic amb Te Matxa de Tea Shop"},"content":{"rendered":"<p>Pa de pessic amb te matxa de Tea Shop. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable.<\/p>\n<p>El 1954 els nostres avis tenien un colmado al costat de la seva petita granja de gallines. Hi venien al ve\u00efnat els ous aix\u00ed com queviures de tota mena. Un cop la botiga es va quedar sense subministrament de magdalenes, un dels seus productes m\u00e9s populars. Per acontentar la clientela, la nostra \u00e0via va decidir enfornar la seva pr\u00f2pia recepta de magdalenes a la cuina de casa seva. El seu enorme \u00e8xit va sorprendre tothom, cada vegada es venien m\u00e9s i m\u00e9s. D&#8217;aqu\u00ed va n\u00e9ixer La Granja i vam aprendre una cosa que sempre tenim present: treballar fort i fer-ho tot el millor que hom sap per satisfer els teus clients.<\/p>\n<p>Va ser aix\u00ed amb les primeres especialitats tradicionals que ens van donar a con\u00e8ixer i ho ha continuat sent al llarg de la nostra traject\u00f2ria, en incorporar cont\u00ednuament novetats a la nostra gamma.<\/p>\n<p>Avan\u00e7ar-nos a les necessitats i desitjos dels consumidors ens ha convertit en un referent de qualitat i innovaci\u00f3 al nostre sector de productes d&#8217;alimentaci\u00f3. Als anys 80 La Granja va ser pionera en crear especialitats atenent a diferents necessitats diet\u00e8tiques, que avui formen part de la nostra gamma Diet.<\/p>\n<p>M\u00e9s tard llancem la gamma Bio, que utilitza nom\u00e9s ingredients de l&#8217;agricultura ecol\u00f2gica. Han seguit aquesta l\u00ednia, la gamma Vegan per a un consum estrictament veg\u00e0 i els productes Sense Gluten i Sense Lactosa, que tenen una producci\u00f3 separada a la resta de productes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avui estem emocionats de presentar-te una col\u00b7laboraci\u00f3 veritablement especial que ha nascut de la uni\u00f3 entre dos mons de sabors: <strong>La Granja\u00a0Foods\u00a0i\u00a0Tea\u00a0Shop.<\/strong><\/p>\n<p>El sabor umami del Matxa i el sabor fresc del Te Verd s&#8217;equilibren amb l&#8217;envolupant dol\u00e7or de la vainilla i les flors. Els seus ingredients combinen amb eleg\u00e0ncia els or\u00edgens modernistes de la ciutat de Barcelona i notes mediterr\u00e0nies.<\/p>\n<p>Tea Shop ens envia el seu Te Verd Matxa, i a La Granja ho triturem per a afegir-ho a la massa, d&#8217;aquesta manera aconseguim un resultat excepcional, amb productes aut\u00e8ntics i naturals. Ja que aquest pa de pessic est\u00e0 lliure de saboritzants, colorants o aromes artificials.<\/p>\n<p>Deliciosa i arom\u00e0tica mescla de\u00a0\u00a0Te Verd, pell de taronja, Te Verd Matxa, p\u00e8tals de blauet, p\u00e8tals de rosa vermella, p\u00e8tals de gira-sol i vainilla.<\/p>\n<ul>\n<li>Amb te real de Tea Shop<\/li>\n<li>Sense colorants o sabors artificials<\/li>\n<li>Elaborat amb iogurt natural<\/li>\n<li>Elaborat amb ous frescos<\/li>\n<li>Enfornat lentament<\/li>\n<li>Elevada esponjositat i sabor<\/li>\n<li>Textura molt tendra<\/li>\n<li>Amb els millors ingredients i de m\u00e0xima qualitat<\/li>\n<\/ul>\n","protected":false},"featured_media":58065,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[432,105],"product_tag":[],"class_list":["post-8903","product","type-product","status-publish","has-post-thumbnail","product_cat-edicions-especials","product_cat-tradicionals","pa_marca-la-granja-ca","pa_tipologia-pa-de-pessic","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pa de pessic amb Te Matxa de Tea Shop - La Granja Foods<\/title>\n<meta name=\"description\" content=\"Pa de pessic amb Te Matcha Tea Shop. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor \u00e9s el nostre objectiu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pa de pessic amb Te Matxa de Tea Shop - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"Pa de pessic amb Te Matcha Tea Shop. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor \u00e9s el nostre objectiu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T10:33:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-de-Matcha-Tea-Shop-857x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"857\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-amb-te-matxa-de-tea-shop\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-amb-te-matxa-de-tea-shop\\\/\",\"name\":\"Pa de pessic amb Te Matxa de Tea Shop - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-amb-te-matxa-de-tea-shop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-amb-te-matxa-de-tea-shop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-de-Matcha-Tea-Shop.png\",\"datePublished\":\"2024-06-06T15:03:56+00:00\",\"dateModified\":\"2026-05-29T10:33:18+00:00\",\"description\":\"Pa de pessic amb Te Matcha Tea Shop. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor \u00e9s el nostre objectiu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-amb-te-matxa-de-tea-shop\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-amb-te-matxa-de-tea-shop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-amb-te-matxa-de-tea-shop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-de-Matcha-Tea-Shop.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-de-Matcha-Tea-Shop.png\",\"width\":1692,\"height\":2022},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-amb-te-matxa-de-tea-shop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productes\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/productes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pa de pessic amb Te Matxa de Tea Shop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pa de pessic amb Te Matxa de Tea Shop - La Granja Foods","description":"Pa de pessic amb Te Matcha Tea Shop. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor \u00e9s el nostre objectiu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/","og_locale":"ca_ES","og_type":"article","og_title":"Pa de pessic amb Te Matxa de Tea Shop - La Granja Foods","og_description":"Pa de pessic amb Te Matcha Tea Shop. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor \u00e9s el nostre objectiu.","og_url":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/","og_site_name":"La Granja Foods","article_modified_time":"2026-05-29T10:33:18+00:00","og_image":[{"width":857,"height":1024,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-de-Matcha-Tea-Shop-857x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"2 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/","url":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/","name":"Pa de pessic amb Te Matxa de Tea Shop - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-de-Matcha-Tea-Shop.png","datePublished":"2024-06-06T15:03:56+00:00","dateModified":"2026-05-29T10:33:18+00:00","description":"Pa de pessic amb Te Matcha Tea Shop. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor \u00e9s el nostre objectiu.","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-de-Matcha-Tea-Shop.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-de-Matcha-Tea-Shop.png","width":1692,"height":2022},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-amb-te-matxa-de-tea-shop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Productes","item":"https:\/\/lagranjafoods.com\/ca\/productes\/"},{"@type":"ListItem","position":3,"name":"Pa de pessic amb Te Matxa de Tea Shop"}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/ca\/#website","url":"https:\/\/lagranjafoods.com\/ca\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/ca\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product\/8903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/comments?post=8903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media\/58065"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media?parent=8903"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_cat?post=8903"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_tag?post=8903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}