{"id":8582,"date":"2024-06-06T13:52:52","date_gmt":"2024-06-06T11:52:52","guid":{"rendered":"http:\/\/lagranjafoods.com\/product\/pa-de-pessic-especial-cava-i-ametlla\/"},"modified":"2026-05-29T12:32:35","modified_gmt":"2026-05-29T10:32:35","slug":"pa-de-pessic-especial-cava-i-ametlla","status":"publish","type":"product","link":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/","title":{"rendered":"Pa de pessic especial cava i ametlla"},"content":{"rendered":"<p>Pa de pessic especial cava i ametlla. Des del primer dia, elaborar els productes el millor que sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable.<\/p>\n<p>L\u2019any 1954, els nostres avis tenien un colmado al costat de la seva petita granja de gallines. Hi venien ous al ve\u00efnat, aix\u00ed com queviures de tota mena. Un dia, la botiga es va quedar sense subministrament de magdalenes, un dels seus productes m\u00e9s populars. Per satisfer la clientela, la nostra \u00e0via va decidir enfornar la seva pr\u00f2pia recepta de magdalenes a la cuina de casa seva. L\u2019\u00e8xit va ser immens i inesperat: cada vegada en venien m\u00e9s i m\u00e9s. D\u2019aqu\u00ed va n\u00e9ixer La Granja, i vam aprendre una lli\u00e7\u00f3 que sempre hem tingut present: treballar de valent i fer les coses tan b\u00e9 com sigui possible per satisfer els nostres clients.<\/p>\n<p>Aix\u00ed va comen\u00e7ar tot, amb les primeres especialitats tradicionals que ens van donar a con\u00e8ixer, i aix\u00ed ha continuat al llarg de la nostra traject\u00f2ria, incorporant cont\u00ednuament novetats a la nostra gamma.<\/p>\n<p>Anticipar-nos a les necessitats i desitjos dels consumidors ens ha convertit en un referent de qualitat i innovaci\u00f3 en el sector de l\u2019alimentaci\u00f3. Als anys 80, La Granja va ser pionera en crear especialitats pensades per a diferents necessitats diet\u00e8tiques, que avui formen part de la nostra Gamma Diet.<\/p>\n<p>M\u00e9s endavant, vam llan\u00e7ar la Gamma Bio, elaborada \u00fanicament amb ingredients provinents de l\u2019agricultura ecol\u00f2gica. Despr\u00e9s van arribar la Gamma Vegan, per a un consum estrictament veg\u00e0, i la Gamma Sense Gluten i Sense Lactosa, amb una producci\u00f3 separada de la resta de productes.<\/p>\n<p>En els productes d\u2019aquesta nova gamma utilitzem \u00fanicament ingredients lliures de gluten, lactosa i blat de moro. Assegurem la seva no-contaminaci\u00f3 durant tot el proc\u00e9s, des d\u2019una producci\u00f3 totalment separada. Aquest producte compta amb el segell de La Espiga Barrada i el n\u00famero de llic\u00e8ncia ES-055-016, certificat per l\u2019AOECS (Associaci\u00f3 de Societats de Cel\u00edacs d\u2019Europa).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sorprenent sabor mediterrani. Un tendre pa de pessic que rendeix homenatge a la nostra terra i uneix les fresques aromes del cava amb el delici\u00f3s sabor de les ametlles mediterr\u00e0nies.<\/p>\n<ul>\n<li>Amb ametlla molta natural<\/li>\n<li>Amb els millors ingredients mediterranis<\/li>\n<li>Elaborat amb ous frescos<\/li>\n<li>Enfornat lentament<\/li>\n<li>Elaborat amb sucre de canya<\/li>\n<li>Textura molt tendra<\/li>\n<\/ul>\n","protected":false},"featured_media":32137,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[105],"product_tag":[426],"class_list":["post-8582","product","type-product","status-publish","has-post-thumbnail","product_cat-tradicionals","product_tag-fruits-secs-ca-2","pa_marca-la-granja-ca","pa_tipologia-pa-de-pessic","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pa de pessic especial cava i ametlla - La Granja Foods<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pa de pessic especial cava i ametlla - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"Sorprenent sabor mediterrani. Un tendre pa de pessic que rendeix homenatge a la nostra terra i uneix les fresques aromes del cava amb el delici\u00f3s sabor de les ametlles mediterr\u00e0nies.   Amb ametlla molta natural  Amb els millors ingredients mediterranis  Elaborat amb ous frescos  Enfornat lentament  Elaborat amb sucre de canya  Textura molt tendra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T10:32:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-Cava-Almendra_Thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1692\" \/>\n\t<meta property=\"og:image:height\" content=\"2022\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-cava-i-ametlla\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-cava-i-ametlla\\\/\",\"name\":\"Pa de pessic especial cava i ametlla - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-cava-i-ametlla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-cava-i-ametlla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-Cava-Almendra_Thumbnail.jpg\",\"datePublished\":\"2024-06-06T11:52:52+00:00\",\"dateModified\":\"2026-05-29T10:32:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-cava-i-ametlla\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-cava-i-ametlla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-cava-i-ametlla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-Cava-Almendra_Thumbnail.jpg\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-Cava-Almendra_Thumbnail.jpg\",\"width\":1692,\"height\":2022},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-cava-i-ametlla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productes\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/productes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pa de pessic especial cava i ametlla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pa de pessic especial cava i ametlla - La Granja Foods","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/","og_locale":"ca_ES","og_type":"article","og_title":"Pa de pessic especial cava i ametlla - La Granja Foods","og_description":"Sorprenent sabor mediterrani. Un tendre pa de pessic que rendeix homenatge a la nostra terra i uneix les fresques aromes del cava amb el delici\u00f3s sabor de les ametlles mediterr\u00e0nies.   Amb ametlla molta natural  Amb els millors ingredients mediterranis  Elaborat amb ous frescos  Enfornat lentament  Elaborat amb sucre de canya  Textura molt tendra","og_url":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/","og_site_name":"La Granja Foods","article_modified_time":"2026-05-29T10:32:35+00:00","og_image":[{"width":1692,"height":2022,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-Cava-Almendra_Thumbnail.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"2 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/","url":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/","name":"Pa de pessic especial cava i ametlla - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-Cava-Almendra_Thumbnail.jpg","datePublished":"2024-06-06T11:52:52+00:00","dateModified":"2026-05-29T10:32:35+00:00","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-Cava-Almendra_Thumbnail.jpg","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-Cava-Almendra_Thumbnail.jpg","width":1692,"height":2022},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-cava-i-ametlla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Productes","item":"https:\/\/lagranjafoods.com\/ca\/productes\/"},{"@type":"ListItem","position":3,"name":"Pa de pessic especial cava i ametlla"}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/ca\/#website","url":"https:\/\/lagranjafoods.com\/ca\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/ca\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product\/8582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/comments?post=8582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media\/32137"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media?parent=8582"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_cat?post=8582"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_tag?post=8582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}