{"id":57479,"date":"2026-06-09T09:08:04","date_gmt":"2026-06-09T07:08:04","guid":{"rendered":"http:\/\/lagranjafoods.com\/?post_type=product&#038;p=57479"},"modified":"2026-07-06T12:03:55","modified_gmt":"2026-07-06T10:03:55","slug":"pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr","status":"publish","type":"product","link":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/","title":{"rendered":"Pa de pessic especial carbassa i iuzu sense gluten i sense lactosa 230 gr."},"content":{"rendered":"<p>Pa de pessic especial carbassa i yuzu sense gluten i sense lactosa 230 gr. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable. Va ser aix\u00ed amb les primeres especialitats tradicionals que ens van donar a con\u00e8ixer i ho ha continuat sent al llarg de la <a href=\"https:\/\/lagranjafoods.com\/ca\/nosaltres-historia\/\">nostra traject\u00f2ria<\/a>, en incorporar cont\u00ednuament novetats a la nostra gamma.<\/p>\n<p>Avan\u00e7ar-nos a les necessitats i desitjos dels consumidors ens ha convertit en un referent de qualitat i innovaci\u00f3 al nostre sector de productes d&#8217;alimentaci\u00f3. Als anys 80 La Granja va ser pionera en crear especialitats atenent a diferents necessitats diet\u00e8tiques, que avui formen part de la nostra gamma Diet. M\u00e9s tard llancem la gamma Bio, que utilitza nom\u00e9s ingredients de l&#8217;agricultura ecol\u00f2gica. Han seguit la gamma Vegan per a un consum estrictament veg\u00e0 i la producci\u00f3 separada de la gamma de productes Sense Gluten.<\/p>\n<p>El 1954 els nostres avis tenien un colmado al costat de la seva petita granja de gallines. Hi venien al ve\u00efnat els ous aix\u00ed com queviures de tota mena.<\/p>\n<p>Un cop la botiga es va quedar sense subministrament de magdalenes, un dels seus productes m\u00e9s populars. Per acontentar la clientela, la nostra \u00e0via va decidir enfornar la seva pr\u00f2pia recepta de magdalenes a la cuina de casa seva.<\/p>\n<p>El seu enorme \u00e8xit va sorprendre tothom, cada vegada es venien m\u00e9s i m\u00e9s. D&#8217;aqu\u00ed va n\u00e9ixer La Granja i vam aprendre una cosa que sempre tenim present: treballar fort i fer-ho tot el millor que hom sap per satisfer els teus clients, nom\u00e9s pot portar coses bones.<\/p>\n<p>Als productes d&#8217;aquesta nova gamma utilitzem \u00fanicament ingredients lliures de gluten, lactosa i blat de moro. Assegurem la seva no contaminaci\u00f3 en tot el proc\u00e9s, des d&#8217;una producci\u00f3 separada de la resta. Aquest producte compta amb el segell de l<a href=\"https:\/\/celiacos.org\/que-hacemos\/certificacion-alimentaria-sin-gluten\/sistema-de-licencia-europeo-els-o-espiga-barrada\/\">&#8216;Espiga Barrada<\/a> i el n\u00famero de llic\u00e8ncia ES-055-005, certificat per\u00a0 l&#8217;AOECS (Associaci\u00f3 de Societats de Cel\u00edacs d&#8217;Europa).<\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"16\" data-end=\"423\">Gaudeix del nostre Bizcocho de Carbassa i Yuzu Sense Gluten en el seu nou format de 230 g, una pr\u00e0ctica bossa amb 4 deliciosos trossos de bizcocho llestos per gaudir en qualsevol moment. La seva textura delicada combina la dol\u00e7or suau de la carbassa amb el toc c\u00edtric i refrescant del yuzu, creant un bizcocho original i ple de matisos. Una opci\u00f3 irresistible per a qui busca sabors diferents i sorprenents.<\/p>\n<ul>\n<li data-start=\"425\" data-end=\"636\">Sense gluten<\/li>\n<li data-start=\"425\" data-end=\"636\">Sense lactosa<\/li>\n<li data-start=\"425\" data-end=\"636\">Sense blat de moro<\/li>\n<li data-start=\"425\" data-end=\"636\">Sense oli de palma<\/li>\n<li data-start=\"425\" data-end=\"636\">Elaborat amb ous frescos<\/li>\n<li data-start=\"425\" data-end=\"636\">Cuit lentament<\/li>\n<li data-start=\"425\" data-end=\"636\">Alta esponjositat i sabor<\/li>\n<li data-start=\"425\" data-end=\"636\">Textura molt tendra<\/li>\n<li data-start=\"425\" data-end=\"636\">Cont\u00e9 fibres vegetals i closca de psyllium<\/li>\n<\/ul>\n<p data-start=\"638\" data-end=\"653\">Bossa de 230 g.<\/p>\n","protected":false},"featured_media":57943,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[106],"product_tag":[632],"class_list":["post-57479","product","type-product","status-publish","has-post-thumbnail","product_cat-sense-gluten","product_tag-sin-gluten","pa_marca-la-granja-ca","pa_tipologia-pa-de-pessic","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pa de pessic especial carbassa i iuzu sense gluten i sense lactosa 230 gr. - La Granja Foods<\/title>\n<meta name=\"description\" content=\"Pa de pessic especial carbassa i yuzu sense gluten i sense lactosa. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pa de pessic especial carbassa i iuzu sense gluten i sense lactosa 230 gr. - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"Pa de pessic especial carbassa i yuzu sense gluten i sense lactosa. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T10:03:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-calabaza-y-yuzu-230g.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1692\" \/>\n\t<meta property=\"og:image:height\" content=\"2022\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\\\/\",\"name\":\"Pa de pessic especial carbassa i iuzu sense gluten i sense lactosa 230 gr. - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-calabaza-y-yuzu-230g.png\",\"datePublished\":\"2026-06-09T07:08:04+00:00\",\"dateModified\":\"2026-07-06T10:03:55+00:00\",\"description\":\"Pa de pessic especial carbassa i yuzu sense gluten i sense lactosa. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-calabaza-y-yuzu-230g.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Bizcocho-calabaza-y-yuzu-230g.png\",\"width\":1692,\"height\":2022},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productes\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/productes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pa de pessic especial carbassa i iuzu sense gluten i sense lactosa 230 gr.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pa de pessic especial carbassa i iuzu sense gluten i sense lactosa 230 gr. - La Granja Foods","description":"Pa de pessic especial carbassa i yuzu sense gluten i sense lactosa. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/","og_locale":"ca_ES","og_type":"article","og_title":"Pa de pessic especial carbassa i iuzu sense gluten i sense lactosa 230 gr. - La Granja Foods","og_description":"Pa de pessic especial carbassa i yuzu sense gluten i sense lactosa. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor.","og_url":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/","og_site_name":"La Granja Foods","article_modified_time":"2026-07-06T10:03:55+00:00","og_image":[{"width":1692,"height":2022,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-calabaza-y-yuzu-230g.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"2 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/","url":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/","name":"Pa de pessic especial carbassa i iuzu sense gluten i sense lactosa 230 gr. - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-calabaza-y-yuzu-230g.png","datePublished":"2026-06-09T07:08:04+00:00","dateModified":"2026-07-06T10:03:55+00:00","description":"Pa de pessic especial carbassa i yuzu sense gluten i sense lactosa. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor.","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-calabaza-y-yuzu-230g.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Bizcocho-calabaza-y-yuzu-230g.png","width":1692,"height":2022},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/pa-de-pessic-especial-carbassa-i-iuzu-sense-gluten-i-sense-lactosa-230gr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Productes","item":"https:\/\/lagranjafoods.com\/ca\/productes\/"},{"@type":"ListItem","position":3,"name":"Pa de pessic especial carbassa i iuzu sense gluten i sense lactosa 230 gr."}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/ca\/#website","url":"https:\/\/lagranjafoods.com\/ca\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/ca\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product\/57479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/comments?post=57479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media\/57943"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media?parent=57479"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_cat?post=57479"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_tag?post=57479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}