{"id":44775,"date":"2026-05-20T12:54:18","date_gmt":"2026-05-20T10:54:18","guid":{"rendered":"http:\/\/lagranjafoods.com\/?post_type=product&#038;p=44775"},"modified":"2026-05-29T13:47:06","modified_gmt":"2026-05-29T11:47:06","slug":"caixa-bombons-de-chocolata-estil-dubai","status":"publish","type":"product","link":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/","title":{"rendered":"Caixa assortida de bombons de xocolata estil Dubai"},"content":{"rendered":"<p data-start=\"1409\" data-end=\"1813\"><strong>Caixa assortida de bombons de xocolata estil Dubai.<\/strong> A <a href=\"https:\/\/lagranjafoods.com\/ca\/nosaltres-historia\/\">La Granja Foods<\/a> sempre busquem productes que sorprenguin i delectin els nostres clients, per aix\u00f2 estem encantats de col\u00b7laborar amb Mi&amp;Cu, una marca especialitzada en la creaci\u00f3 dels inigualables bombons Marlonas. Aquests bombons s\u2019han guanyat un lloc especial en el m\u00f3n de la confiteria gr\u00e0cies a la seva distintiva combinaci\u00f3 de sabors i textures.<\/p>\n<p data-start=\"1815\" data-end=\"2162\">Mi&amp;Cu es distingeix per la seva innovaci\u00f3 i dedicaci\u00f3 a l\u2019excel\u00b7l\u00e8ncia, utilitzant nom\u00e9s els ingredients m\u00e9s selectes per crear bombons que no nom\u00e9s tenen un sabor excepcional, sin\u00f3 que tamb\u00e9 expliquen una hist\u00f2ria de passi\u00f3 per la xocolata. Ara tens l\u2019oportunitat d\u2019experimentar la m\u00e0gia dels bombons Marlonas a trav\u00e9s de la nostra botiga online.<\/p>\n<p data-start=\"2164\" data-end=\"2448\">Des de sabors cl\u00e0ssics fins a combinacions m\u00e9s atrevides, cada bomb\u00f3 <a href=\"https:\/\/lagranjafoods.com\/ca\/Marca\/bombones-micu-ca\/\">Marlonas<\/a> \u00e9s una obra mestra de sabor que ofereix una experi\u00e8ncia gustativa \u00fanica. Ens complau formar part d\u2019aquesta deliciosa aventura, portant-te un producte que redefineix qu\u00e8 significa gaudir d\u2019una bona xocolata.<\/p>\n<p data-start=\"2450\" data-end=\"2723\">MI&amp;CU Gourmet \u00e9s una empresa familiar situada a prop de Barcelona fundada pels germans Miret, la N\u00faria i en Josep. Provenen d\u2019una llarga tradici\u00f3 familiar vinculada a la xocolata de m\u00e9s de 70 anys i acumulen m\u00e9s de 20 anys d\u2019experi\u00e8ncia en el sector de la xocolata gourmet.<\/p>\n<p data-start=\"2725\" data-end=\"2883\" data-is-last-node=\"\" data-is-only-node=\"\">En els nostres productes combinem l\u2019\u00fas de mat\u00e8ries primeres mediterr\u00e0nies de qualitat, principalment les ametlles, amb sabors cl\u00e0ssics, com la gamma Marlonas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"isSelectedEnd\">Regala\u2019t un caprici gaudint d\u2019aquestes del\u00edcies de xocolata amb un interior farcit de pralin\u00e9 de festuc i cruixent de kataifi. Una combinaci\u00f3 irresistible de textures i sabors inspirada en l\u2019eleg\u00e0ncia i sofisticaci\u00f3 de la rebosteria oriental.<\/p>\n<p class=\"isSelectedEnd\">Aquest producte \u00e9s sense gluten!<\/p>\n<ul>\n<li class=\"isSelectedEnd\">Sense gluten<\/li>\n<li class=\"isSelectedEnd\">Amb la millor selecci\u00f3 de festucs<\/li>\n<li class=\"isSelectedEnd\">Amb ingredients de m\u00e0xima qualitat<\/li>\n<li class=\"isSelectedEnd\">Coberts d\u2019una capa de xocolata<\/li>\n<li class=\"isSelectedEnd\">Elaborats amb xocolata premium<\/li>\n<li class=\"isSelectedEnd\">Tres xocolates per triar<\/li>\n<\/ul>\n<p>Caixa de 210 g.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":46319,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[112],"product_tag":[641],"class_list":["post-44775","product","type-product","status-publish","has-post-thumbnail","product_cat-marques-amigues","product_tag-chocolate","pa_marca-bombones-micu-ca","pa_marca-la-granja-ca","pa_tipologia-bombons","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caixa assortida de bombons de xocolata estil Dubai - La Granja Foods<\/title>\n<meta name=\"description\" content=\"Caixa assortida de bombons de xocolata estil Dubai. Sempre busquem sorprendre els nostres clients, per aix\u00f2 estem encantats de col\u00b7laborar amb Mi&amp;Cu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caixa assortida de bombons de xocolata estil Dubai - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"Caixa assortida de bombons de xocolata estil Dubai. Sempre busquem sorprendre els nostres clients, per aix\u00f2 estem encantats de col\u00b7laborar amb Mi&amp;Cu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T11:47:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/50.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1692\" \/>\n\t<meta property=\"og:image:height\" content=\"2022\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-bombons-de-chocolata-estil-dubai\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-bombons-de-chocolata-estil-dubai\\\/\",\"name\":\"Caixa assortida de bombons de xocolata estil Dubai - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-bombons-de-chocolata-estil-dubai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-bombons-de-chocolata-estil-dubai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/50.png\",\"datePublished\":\"2026-05-20T10:54:18+00:00\",\"dateModified\":\"2026-05-29T11:47:06+00:00\",\"description\":\"Caixa assortida de bombons de xocolata estil Dubai. Sempre busquem sorprendre els nostres clients, per aix\u00f2 estem encantats de col\u00b7laborar amb Mi&Cu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-bombons-de-chocolata-estil-dubai\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-bombons-de-chocolata-estil-dubai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-bombons-de-chocolata-estil-dubai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/50.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/50.png\",\"width\":1692,\"height\":2022},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-bombons-de-chocolata-estil-dubai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productes\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/productes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caixa assortida de bombons de xocolata estil Dubai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caixa assortida de bombons de xocolata estil Dubai - La Granja Foods","description":"Caixa assortida de bombons de xocolata estil Dubai. Sempre busquem sorprendre els nostres clients, per aix\u00f2 estem encantats de col\u00b7laborar amb Mi&Cu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/","og_locale":"ca_ES","og_type":"article","og_title":"Caixa assortida de bombons de xocolata estil Dubai - La Granja Foods","og_description":"Caixa assortida de bombons de xocolata estil Dubai. Sempre busquem sorprendre els nostres clients, per aix\u00f2 estem encantats de col\u00b7laborar amb Mi&Cu.","og_url":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/","og_site_name":"La Granja Foods","article_modified_time":"2026-05-29T11:47:06+00:00","og_image":[{"width":1692,"height":2022,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/50.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"2 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/","url":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/","name":"Caixa assortida de bombons de xocolata estil Dubai - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/50.png","datePublished":"2026-05-20T10:54:18+00:00","dateModified":"2026-05-29T11:47:06+00:00","description":"Caixa assortida de bombons de xocolata estil Dubai. Sempre busquem sorprendre els nostres clients, per aix\u00f2 estem encantats de col\u00b7laborar amb Mi&Cu.","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/50.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/50.png","width":1692,"height":2022},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-bombons-de-chocolata-estil-dubai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Productes","item":"https:\/\/lagranjafoods.com\/ca\/productes\/"},{"@type":"ListItem","position":3,"name":"Caixa assortida de bombons de xocolata estil Dubai"}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/ca\/#website","url":"https:\/\/lagranjafoods.com\/ca\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/ca\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product\/44775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/comments?post=44775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media\/46319"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media?parent=44775"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_cat?post=44775"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_tag?post=44775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}