{"id":35180,"date":"2024-09-04T09:08:08","date_gmt":"2024-09-04T07:08:08","guid":{"rendered":"http:\/\/lagranjafoods.com\/?post_type=product&#038;p=35180"},"modified":"2026-05-29T12:34:32","modified_gmt":"2026-05-29T10:34:32","slug":"caixa-1-5-kg-madalenas-tradicionals-originals","status":"publish","type":"product","link":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/","title":{"rendered":"Caixa Magdalenes Tradicionals Originals 30uds"},"content":{"rendered":"<p>Magdalenes tradicionals originals 30 uds. Des del primer dia, elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable.<\/p>\n<p>El 1954 els nostres avis tenien un colmado al costat de la seva petita granja de gallines. Hi venien al ve\u00efnat els ous aix\u00ed com queviures de tota mena. Un cop la botiga es va quedar sense subministrament de magdalenes, un dels seus productes m\u00e9s populars. Per acontentar la clientela, la nostra \u00e0via va decidir enfornar la seva pr\u00f2pia recepta de magdalenes a la cuina de casa seva. El seu enorme \u00e8xit va sorprendre tothom, cada vegada es venien m\u00e9s i m\u00e9s. D&#8217;aqu\u00ed va n\u00e9ixer La Granja i vam aprendre una cosa que sempre tenim present: treballar fort i fer-ho tot el millor que hom sap per satisfer els teus clients.<\/p>\n<p>Va ser aix\u00ed amb les primeres especialitats tradicionals que ens van donar a con\u00e8ixer i ho ha continuat sent al llarg de la nostra traject\u00f2ria, en incorporar cont\u00ednuament novetats a la nostra gamma.<\/p>\n<p>Avan\u00e7ar-nos a les necessitats i desitjos dels consumidors ens ha convertit en un referent de qualitat i innovaci\u00f3 al nostre sector de productes d&#8217;alimentaci\u00f3. Als anys 80 La Granja va ser pionera en crear especialitats atenent a diferents necessitats diet\u00e8tiques, que avui formen part de la nostra gamma Diet.<\/p>\n<p>M\u00e9s tard llancem la gamma Bio, que nom\u00e9s utilitza ingredients de l&#8217;agricultura ecol\u00f2gica. Han seguit aquesta l\u00ednia, la gamma Vegan per a un consum estrictament veg\u00e0 i els productes Sense Gluten i Sense Lactosa, que tenen una producci\u00f3 separada a la resta de productes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"\" data-start=\"69\" data-end=\"194\">Els millors ingredients i un forn prec\u00eds donen a aquestes magdalenes tot el sabor i la textura de la nostra recepta familiar.<\/p>\n<p class=\"\" data-start=\"196\" data-end=\"480\">Oferim aquestes delicioses Magdalenes tradicionals originals en diferents formats per adaptar-nos a les teves necessitats. Pots escollir el format en Caixa d\u20191,5 kg amb 35 porcions embolicades individualment: perfecta per emportar o per gaudir d\u2019una porci\u00f3 fresca en qualsevol moment.<\/p>\n<ul>\n<li aria-level=\"1\">Elaborat amb ous frescos<\/li>\n<li aria-level=\"1\">Enfornats lentament<\/li>\n<li aria-level=\"1\">Elevada esponjositat i sabor<\/li>\n<li aria-level=\"1\">Textura molt tendra<\/li>\n<li aria-level=\"1\">Amb els millors ingredients i de m\u00e0xima qualitat<\/li>\n<\/ul>\n","protected":false},"featured_media":39154,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[105],"product_tag":[],"class_list":["post-35180","product","type-product","status-publish","has-post-thumbnail","product_cat-tradicionals","pa_marca-la-granja-ca","pa_tipologia-magdalenes","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caixa Magdalenes Tradicionals Originals 30uds - La Granja Foods<\/title>\n<meta name=\"description\" content=\"Magdalenes tradicionals originals 1,5Kg. Elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caixa Magdalenes Tradicionals Originals 30uds - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"Magdalenes tradicionals originals 1,5Kg. Elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T10:34:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/fotografia-producto-pagina-web-23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1692\" \/>\n\t<meta property=\"og:image:height\" content=\"2022\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-1-5-kg-madalenas-tradicionals-originals\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-1-5-kg-madalenas-tradicionals-originals\\\/\",\"name\":\"Caixa Magdalenes Tradicionals Originals 30uds - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-1-5-kg-madalenas-tradicionals-originals\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-1-5-kg-madalenas-tradicionals-originals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/fotografia-producto-pagina-web-23.jpg\",\"datePublished\":\"2024-09-04T07:08:08+00:00\",\"dateModified\":\"2026-05-29T10:34:32+00:00\",\"description\":\"Magdalenes tradicionals originals 1,5Kg. Elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-1-5-kg-madalenas-tradicionals-originals\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-1-5-kg-madalenas-tradicionals-originals\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-1-5-kg-madalenas-tradicionals-originals\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/fotografia-producto-pagina-web-23.jpg\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/fotografia-producto-pagina-web-23.jpg\",\"width\":1692,\"height\":2022},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/producte\\\/caixa-1-5-kg-madalenas-tradicionals-originals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productes\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/productes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caixa Magdalenes Tradicionals Originals 30uds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caixa Magdalenes Tradicionals Originals 30uds - La Granja Foods","description":"Magdalenes tradicionals originals 1,5Kg. Elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/","og_locale":"ca_ES","og_type":"article","og_title":"Caixa Magdalenes Tradicionals Originals 30uds - La Granja Foods","og_description":"Magdalenes tradicionals originals 1,5Kg. Elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable.","og_url":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/","og_site_name":"La Granja Foods","article_modified_time":"2026-05-29T10:34:32+00:00","og_image":[{"width":1692,"height":2022,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/fotografia-producto-pagina-web-23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"2 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/","url":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/","name":"Caixa Magdalenes Tradicionals Originals 30uds - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/fotografia-producto-pagina-web-23.jpg","datePublished":"2024-09-04T07:08:08+00:00","dateModified":"2026-05-29T10:34:32+00:00","description":"Magdalenes tradicionals originals 1,5Kg. Elaborar els productes tan b\u00e9 com sabem i assegurar un gran sabor ha estat per a nosaltres un valor irrenunciable.","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/fotografia-producto-pagina-web-23.jpg","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/fotografia-producto-pagina-web-23.jpg","width":1692,"height":2022},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/ca\/producte\/caixa-1-5-kg-madalenas-tradicionals-originals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Productes","item":"https:\/\/lagranjafoods.com\/ca\/productes\/"},{"@type":"ListItem","position":3,"name":"Caixa Magdalenes Tradicionals Originals 30uds"}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/ca\/#website","url":"https:\/\/lagranjafoods.com\/ca\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/ca\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product\/35180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/comments?post=35180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media\/39154"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media?parent=35180"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_cat?post=35180"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/product_tag?post=35180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}