{"id":37466,"date":"2022-10-24T11:37:45","date_gmt":"2022-10-24T09:37:45","guid":{"rendered":"http:\/\/lagranjafoods.com\/mermelada-de-calabaza-sin-azucares-anadidos\/"},"modified":"2025-01-31T15:19:59","modified_gmt":"2025-01-31T15:19:59","slug":"mermelada-de-calabaza-sin-azucares-anadidos","status":"publish","type":"post","link":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/","title":{"rendered":"Melmelada de Carbassa Sense Sucre Afegit"},"content":{"rendered":"<h2><span style=\"font-weight: 400;\">INGREDIENTES<\/span><\/h2>\n<ul>\n<li>Pa de Pessic Diet de Nous La Granja<\/li>\n<li>500 gr de carbassa pelada i sense llavors<\/li>\n<li>2 fulls de gelatina<\/li>\n<li>La pell ratllada d&#8217;1\/2 taronja<\/li>\n<li>1 cullerada de canyella en pols<\/li>\n<li>1\/2 culleradeta de gingebre en pols<\/li>\n<li>Suc d&#8217;1 llim\u00f3<\/li>\n<li>Edulcorant al gust<\/li>\n<\/ul>\n<h2>ELABORACI\u00d3<\/h2>\n<ol>\n<li>En una olla, afegeix la carbassa tallada a trossos (pr\u00e8viament pelada i sense llavors) amb mig litre d\u2019aigua. Afegeix la pell de llimona ratllada, la canyella, el gingebre en pols, el suc de llim\u00f3 i l\u2019edulcorant al gust. Cuina tot durant 30 minuts a foc mitj\u00e0 fins que la carbassa estigui feta i tendra.<\/li>\n<li>Hidrata les 2 l\u00e0mines de gelatina en aigua freda durant 5-6<span style=\"font-size: revert; color: initial;\"> minuts. Un cop hidratades, afegeix-les en un got amb dues cullerades d\u2019aigua i escalfa-ho al microones durant 30 segons. Veur\u00e0s que la gelatina s\u2019ha desfet. Amb una cullereta, remou la mescla perqu\u00e8 la gelatina estigui ben dissolta.<\/span><\/li>\n<li>Afegeix la gelatina desfeta a l\u2019olla de la carbassa cuita.<\/li>\n<li>Amb un batedor, tritura tota la mescla a l\u2019olla fins aconseguir una textura fina i homog\u00e8nia. Deixa reposar fins que la mescla arribi a temperatura ambient.<\/li>\n<li>Un cop la melmelada estigui a temperatura ambient, \u00e9s el moment d\u2019introduir-la en pots o recipients per conservar-la a la nevera durant 4-6 hores perqu\u00e8 la gelatina qualli.<\/li>\n<li>Unta la melmelada de carbassa sense sucres afegits sobre el Pa de Pessic Diet de Nous La Granja, \u00e9s la millor combinaci\u00f3 possible!<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>INGREDIENTES Pa de Pessic Diet de Nous La Granja 500 gr de carbassa pelada i sense llavors 2 fulls de gelatina La pell ratllada d&#8217;1\/2 taronja 1 cullerada de canyella &hellip;<\/p>\n","protected":false},"author":1,"featured_media":851,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[82],"tags":[],"class_list":["post-37466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-receptes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Melmelada de Carbassa Sense Sucre Afegit - La Granja Foods<\/title>\n<meta name=\"description\" content=\"INGREDIENTES Pa de Pessic Diet de Nous La Granja 500 gr de carbassa pelada i sense llavors 2 fulls de gelatina La pell ratllada d&#039;1\/2 taronja 1 cullerada\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Melmelada de Carbassa Sense Sucre Afegit - La Granja Foods\" \/>\n<meta property=\"og:description\" content=\"INGREDIENTES Pa de Pessic Diet de Nous La Granja 500 gr de carbassa pelada i sense llavors 2 fulls de gelatina La pell ratllada d&#039;1\/2 taronja 1 cullerada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/\" \/>\n<meta property=\"og:site_name\" content=\"La Granja Foods\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-24T09:37:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-31T15:19:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Banner-recetario-2000-\u00d7-1500-px-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"emfasi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"emfasi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/\"},\"author\":{\"name\":\"emfasi\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/person\\\/8620ca73cfc2e9a8afd326de202a03db\"},\"headline\":\"Melmelada de Carbassa Sense Sucre Afegit\",\"datePublished\":\"2022-10-24T09:37:45+00:00\",\"dateModified\":\"2025-01-31T15:19:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/\"},\"wordCount\":244,\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Banner-recetario-2000-\u00d7-1500-px-5.jpg\",\"articleSection\":[\"Receptes\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/\",\"name\":\"Melmelada de Carbassa Sense Sucre Afegit - La Granja Foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Banner-recetario-2000-\u00d7-1500-px-5.jpg\",\"datePublished\":\"2022-10-24T09:37:45+00:00\",\"dateModified\":\"2025-01-31T15:19:59+00:00\",\"description\":\"INGREDIENTES Pa de Pessic Diet de Nous La Granja 500 gr de carbassa pelada i sense llavors 2 fulls de gelatina La pell ratllada d'1\\\/2 taronja 1 cullerada\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Banner-recetario-2000-\u00d7-1500-px-5.jpg\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/Banner-recetario-2000-\u00d7-1500-px-5.jpg\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/mermelada-de-calabaza-sin-azucares-anadidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Melmelada de Carbassa Sense Sucre Afegit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"name\":\"La Granja Foods\",\"description\":\"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#organization\",\"name\":\"La Granja Foods\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"contentUrl\":\"https:\\\/\\\/lagranjafoods.com\\\/wp-content\\\/uploads\\\/logo-lagranjafoods.png\",\"width\":539,\"height\":158,\"caption\":\"La Granja Foods \"},\"image\":{\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lagranjafoods.com\\\/ca\\\/#\\\/schema\\\/person\\\/8620ca73cfc2e9a8afd326de202a03db\",\"name\":\"emfasi\",\"sameAs\":[\"http:\\\/\\\/lagranjafoods.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Melmelada de Carbassa Sense Sucre Afegit - La Granja Foods","description":"INGREDIENTES Pa de Pessic Diet de Nous La Granja 500 gr de carbassa pelada i sense llavors 2 fulls de gelatina La pell ratllada d'1\/2 taronja 1 cullerada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/","og_locale":"ca_ES","og_type":"article","og_title":"Melmelada de Carbassa Sense Sucre Afegit - La Granja Foods","og_description":"INGREDIENTES Pa de Pessic Diet de Nous La Granja 500 gr de carbassa pelada i sense llavors 2 fulls de gelatina La pell ratllada d'1\/2 taronja 1 cullerada","og_url":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/","og_site_name":"La Granja Foods","article_published_time":"2022-10-24T09:37:45+00:00","article_modified_time":"2025-01-31T15:19:59+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Banner-recetario-2000-\u00d7-1500-px-5.jpg","type":"image\/jpeg"}],"author":"emfasi","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"emfasi","Temps estimat de lectura":"2 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/#article","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/"},"author":{"name":"emfasi","@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/person\/8620ca73cfc2e9a8afd326de202a03db"},"headline":"Melmelada de Carbassa Sense Sucre Afegit","datePublished":"2022-10-24T09:37:45+00:00","dateModified":"2025-01-31T15:19:59+00:00","mainEntityOfPage":{"@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/"},"wordCount":244,"publisher":{"@id":"https:\/\/lagranjafoods.com\/ca\/#organization"},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Banner-recetario-2000-\u00d7-1500-px-5.jpg","articleSection":["Receptes"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/","url":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/","name":"Melmelada de Carbassa Sense Sucre Afegit - La Granja Foods","isPartOf":{"@id":"https:\/\/lagranjafoods.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/#primaryimage"},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Banner-recetario-2000-\u00d7-1500-px-5.jpg","datePublished":"2022-10-24T09:37:45+00:00","dateModified":"2025-01-31T15:19:59+00:00","description":"INGREDIENTES Pa de Pessic Diet de Nous La Granja 500 gr de carbassa pelada i sense llavors 2 fulls de gelatina La pell ratllada d'1\/2 taronja 1 cullerada","breadcrumb":{"@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/#primaryimage","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Banner-recetario-2000-\u00d7-1500-px-5.jpg","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/Banner-recetario-2000-\u00d7-1500-px-5.jpg","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/lagranjafoods.com\/ca\/mermelada-de-calabaza-sin-azucares-anadidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranjafoods.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Melmelada de Carbassa Sense Sucre Afegit"}]},{"@type":"WebSite","@id":"https:\/\/lagranjafoods.com\/ca\/#website","url":"https:\/\/lagranjafoods.com\/ca\/","name":"La Granja Foods","description":"\u00a1Benvinguts a La Granja! Qualitat, sabor i frescor des de 1959.","publisher":{"@id":"https:\/\/lagranjafoods.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranjafoods.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagranjafoods.com\/ca\/#organization","name":"La Granja Foods","url":"https:\/\/lagranjafoods.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","contentUrl":"https:\/\/lagranjafoods.com\/wp-content\/uploads\/logo-lagranjafoods.png","width":539,"height":158,"caption":"La Granja Foods "},"image":{"@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lagranjafoods.com\/ca\/#\/schema\/person\/8620ca73cfc2e9a8afd326de202a03db","name":"emfasi","sameAs":["http:\/\/lagranjafoods.com"]}]}},"_links":{"self":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/posts\/37466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/comments?post=37466"}],"version-history":[{"count":0,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/posts\/37466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media\/851"}],"wp:attachment":[{"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/media?parent=37466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/categories?post=37466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagranjafoods.com\/ca\/wp-json\/wp\/v2\/tags?post=37466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}